{"id":1169,"count":1,"description":"","link":"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/","name":"whales sao miguel","slug":"whales-sao-miguel","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>whales sao miguel Archives - Azores Whales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"whales sao miguel Archives - Azores Whales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/\" \/>\n<meta property=\"og:site_name\" content=\"Azores Whales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#website\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"name\":\"Azores Whales\",\"description\":\"Azores Whale Watching Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/whalewatchingazores.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/#webpage\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/\",\"name\":\"whales sao miguel Archives - Azores Whales\",\"isPartOf\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/tag\/whales-sao-miguel\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/tags\/1169"}],"collection":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts?tags=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}