{"id":61317,"date":"2021-06-11T17:56:11","date_gmt":"2021-06-11T18:56:11","guid":{"rendered":"https:\/\/whalewatchingazores.com\/blog\/?p=61317"},"modified":"2021-06-11T17:56:16","modified_gmt":"2021-06-11T18:56:16","slug":"short-finned-pilot-whales-for-the-third-consecutive-day","status":"publish","type":"post","link":"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/","title":{"rendered":"Short-finned pilot whales for the third consecutive day!"},"content":{"rendered":"\n<p>On a lovely sunny Friday morning we left the harbour with the excitement of a small child to see what the Azorean waters had in store for us.<br>Within minutes of leaving the harbour, both in the morning and in the afternoon we had our first sighting, a not very large group of common dolphins.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16.png\" alt=\"\" data-id=\"61318\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61318\" class=\"wp-image-61318\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-16-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18.png\" alt=\"\" data-id=\"61320\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61320\" class=\"wp-image-61320\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-18-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>The individuals appeared when we were not expecting them and showed us their characteristic yellow hourglass pattern. It was incredible to come across this species that always gives us so much.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3.png\" alt=\"\" data-id=\"61322\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61322\" class=\"wp-image-61322\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-3-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7.png\" alt=\"\" data-id=\"61324\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61324\" class=\"wp-image-61324\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-7-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9.png\" alt=\"\" data-id=\"61326\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61326\" class=\"wp-image-61326\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-9-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11.png\" alt=\"\" data-id=\"61328\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61328\" class=\"wp-image-61328\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-11-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17.png\" alt=\"\" data-id=\"61330\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61330\" class=\"wp-image-61330\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-17-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Once we left the dolphins, our lookout informed us that there were pilot whales in the southwest area of the island, so we changed our course and went there. It is always important to take the opportunity to see stationary species that are not seen all year round in our waters, such as the short-finned pilot whales. We spotted four subgroups of individuals that stayed calmly on the surface breathing and resting, doing some short dives. All the people who were on the catamaran today can say that they were lucky, as this species does not usually stay so close to us, let alone approach us.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2.png\" alt=\"\" data-id=\"61334\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61334\" class=\"wp-image-61334\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-2-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4.png\" alt=\"\" data-id=\"61336\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61336\" class=\"wp-image-61336\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-4-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5.png\" alt=\"\" data-id=\"61338\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61338\" class=\"wp-image-61338\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-5-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6.png\" alt=\"\" data-id=\"61340\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61340\" class=\"wp-image-61340\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-6-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8.png\" alt=\"\" data-id=\"61342\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61342\" class=\"wp-image-61342\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-8-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>And not only the morning people can say that, but the afternoon guests also had the opportunity to see two of the morning subgroups.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-10.png\" alt=\"\" class=\"wp-image-61344\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-10.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-10-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-10-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-10-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-10-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>After today we can confirm that summer is coming and what better way to enjoy it than on the high seas with amazing animals. Hurry up and !<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-19.png\" alt=\"\" class=\"wp-image-61332\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-19.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-19-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-19-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-19-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-19-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12.png\" alt=\"\" data-id=\"61346\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61346\" class=\"wp-image-61346\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-12-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13.png\" alt=\"\" data-id=\"61348\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61348\" class=\"wp-image-61348\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-13-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14.png\" alt=\"\" data-id=\"61350\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61350\" class=\"wp-image-61350\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-14-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15.png\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15.png\" alt=\"\" data-id=\"61352\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=61352\" class=\"wp-image-61352\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-15-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img width=\"900\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-1.png\" alt=\"\" class=\"wp-image-61354\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-1.png 900w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-1-300x200.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-1-768x512.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-1-380x253.png 380w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-dolphins-whales-acores-1-800x533.png 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"On a lovely sunny Friday morning we left the harbour with the excitement of a small child to&hellip;\n","protected":false},"author":3,"featured_media":61357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[308,393],"tags":[33,622,14,11,124],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Short-finned pilot whales for the third consecutive day! - Azores Whales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Short-finned pilot whales for the third consecutive day! - Azores Whales\" \/>\n<meta property=\"og:description\" content=\"On a lovely sunny Friday morning we left the harbour with the excitement of a small child to&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Azores Whales\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-11T18:56:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-11T18:56:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-whales-dolphins-azores.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"5 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#website\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"name\":\"Azores Whales\",\"description\":\"Azores Whale Watching Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/whalewatchingazores.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-whales-dolphins-azores.png\",\"contentUrl\":\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2021\/06\/futurismo-whales-dolphins-azores.png\",\"width\":800,\"height\":600,\"caption\":\"futurismo whales dolphins azores\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/#webpage\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/\",\"name\":\"Short-finned pilot whales for the third consecutive day! - Azores Whales\",\"isPartOf\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/#primaryimage\"},\"datePublished\":\"2021-06-11T18:56:11+00:00\",\"dateModified\":\"2021-06-11T18:56:16+00:00\",\"author\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#\/schema\/person\/56547e320e77468c23cbe993eba1dca3\"},\"breadcrumb\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/short-finned-pilot-whales-for-the-third-consecutive-day\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#\/schema\/person\/56547e320e77468c23cbe993eba1dca3\",\"name\":\"Sandrina Rodrigues\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eb4eea0b283ed9c00d9db8ec28a13051?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eb4eea0b283ed9c00d9db8ec28a13051?s=96&d=mm&r=g\",\"caption\":\"Sandrina Rodrigues\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts\/61317"}],"collection":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/comments?post=61317"}],"version-history":[{"count":2,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts\/61317\/revisions"}],"predecessor-version":[{"id":61361,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts\/61317\/revisions\/61361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/media\/61357"}],"wp:attachment":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/media?parent=61317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/categories?post=61317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/tags?post=61317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}