{"id":53997,"date":"2020-08-31T14:10:00","date_gmt":"2020-08-31T15:10:00","guid":{"rendered":"https:\/\/whalewatchingazores.com\/blog\/?p=53997"},"modified":"2020-08-31T15:08:00","modified_gmt":"2020-08-31T16:08:00","slug":"5-cetacean-species-with-a-surprise-a-minke-whale","status":"publish","type":"post","link":"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/","title":{"rendered":"5 cetacean species with a surprise: a Minke whale!"},"content":{"rendered":"\n<p>Today we observed lots of biodiversity in the Azorean waters! Our small boats and our catamarans saw various different cetacean species this morning. <\/p>\n\n\n\n<p>On the catamarans we started our trip with a charismatic group of our resident species &#8211; <a href=\"https:\/\/whalewatchingazores.com\/blog\/2007\/07\/common-dolphin\/\">common dolphins<\/a>! The dolphins were approaching our boat really close, bowriding in front of us and jumping many times! The reason behind these jumps is not always clear, but some of the explanations are getting rid of parasites or remora fish attached to the dolphins&#8217; bodies, communicating or.. maybe just having fun? Well, we surely did have fun observing them!<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/14-14.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/14-14.png\" alt=\"\" data-id=\"54000\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54000\" class=\"wp-image-54000\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/14-14.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/14-14-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/14-14-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/14-14-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/14-14-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/4-20.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/4-20.png\" alt=\"\" data-id=\"54008\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54008\" class=\"wp-image-54008\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/4-20.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/4-20-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/4-20-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/4-20-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/4-20-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/7-20.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/7-20.png\" alt=\"\" data-id=\"54010\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54010\" class=\"wp-image-54010\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/7-20.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/7-20-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/7-20-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/7-20-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/7-20-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/9-23.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/9-23.png\" alt=\"\" data-id=\"54012\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54012\" class=\"wp-image-54012\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/9-23.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/9-23-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/9-23-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/9-23-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/9-23-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7.png\" alt=\"\" data-id=\"54033\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/2020\/08\/5-cetacean-species-with-a-surprise-a-minke-whale\/21-7\/\" class=\"wp-image-54033\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/21-7-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>After the common dolphins, some much larger animals were there for us. Our beloved <a href=\"https:\/\/whalewatchingazores.com\/blog\/2007\/07\/sperm-whale\/\">sperm whales<\/a> &#8211; the largest toothed animals in the world! First, we saw one whale which soon dived showing us its beautiful tail, but fortunately we also found another&nbsp; one &#8211; which was calmly breathing on the surface for a while, finally lifting its tail as well! We said goodbye to these lovely whales and headed back to Ponta Delgada. <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/8-22.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/8-22.png\" alt=\"\" data-id=\"54014\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54014\" class=\"wp-image-54014\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/8-22.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/8-22-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/8-22-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/8-22-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/8-22-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/10-21.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/10-21.png\" alt=\"\" data-id=\"54016\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54016\" class=\"wp-image-54016\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/10-21.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/10-21-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/10-21-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/10-21-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/10-21-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-17.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-17.png\" alt=\"\" data-id=\"54018\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54018\" class=\"wp-image-54018\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-17.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-17-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-17-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-17-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-17-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-18.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-18.png\" alt=\"\" data-id=\"54020\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54020\" class=\"wp-image-54020\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-18.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-18-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-18-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-18-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-18-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11.png\" alt=\"\" data-id=\"54035\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/2020\/08\/5-cetacean-species-with-a-surprise-a-minke-whale\/19-11\/\" class=\"wp-image-54035\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/19-11-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8.png\" alt=\"\" data-id=\"54037\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/2020\/08\/5-cetacean-species-with-a-surprise-a-minke-whale\/20-8-2\/\" class=\"wp-image-54037\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/20-8-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>But these species were not everything we saw today &#8211; our zodiac was really lucky to see a species we haven&#8217;t seen this year yet &#8211; a <a href=\"https:\/\/whalewatchingazores.com\/blog\/2007\/07\/minke-whale\/\">minke whale<\/a>! This is one of the smallest whale species, with an average length of 7-9 meters &#8211; so not exactly that small for us! <\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16.png\" alt=\"\" data-id=\"53998\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=53998\" class=\"wp-image-53998\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/11-16-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17.png\" alt=\"\" data-id=\"54002\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54002\" class=\"wp-image-54002\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/12-17-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15.png\" alt=\"\" data-id=\"54006\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54006\" class=\"wp-image-54006\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-15-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Also, the small boat enjoyed the presence of <a href=\"https:\/\/whalewatchingazores.com\/blog\/2007\/07\/bottlenose-dolphin\/\">bottlenose dolphins<\/a> &#8211; another resident dolphin species, and one the largest ones we can see here, reaching 4 meters in length.<\/p>\n\n\n\n<p>Our biodiversity didn&#8217;t stop surprising us today, and on the swimming with dolphins trips we managed to see even three dolphin species &#8211; the previously mentioned common, bottlenose, and in addition &#8211; <a href=\"https:\/\/whalewatchingazores.com\/blog\/2007\/07\/atlantic-spotted-dolphin\/\">Atlantic spotted dolphins<\/a>, our seasonal species of the warmer months! The last ones were really active and gave us a great show, some of them circling around our swimmers and letting them enjoy a really close look.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/15-13.png\" alt=\"\" class=\"wp-image-54004\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/15-13.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/15-13-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/15-13-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/15-13-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/15-13-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<p>In total, we saw even 5 cetacean species &#8211; of which 3 resident (sperm whales, bottlenose dolphins and common dolphins), one seasonal (Atlantic spotted dolphins) and one special surprise of a migratory minke whale! A great demonstration of the richness of the ocean surrounding us. <a href=\"https:\/\/whalewatchingazores.com\/en\/whale-dolphin-watching-tours\/whale-and-dolphin-watching-in-ponta-delgada\/\">Join us on our next trip<\/a>!<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/5-21.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/5-21.png\" alt=\"\" data-id=\"54022\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54022\" class=\"wp-image-54022\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/5-21.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/5-21-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/5-21-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/5-21-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/5-21-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/6-19.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/6-19.png\" alt=\"\" data-id=\"54024\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54024\" class=\"wp-image-54024\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/6-19.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/6-19-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/6-19-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/6-19-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/6-19-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-16.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-16.png\" alt=\"\" data-id=\"54026\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/?attachment_id=54026\" class=\"wp-image-54026\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-16.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-16-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-16-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-16-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/13-16-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12.png\" alt=\"\" data-id=\"54039\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/2020\/08\/5-cetacean-species-with-a-surprise-a-minke-whale\/17-12\/\" class=\"wp-image-54039\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/17-12-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12.png\" alt=\"\" data-id=\"54041\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/2020\/08\/5-cetacean-species-with-a-surprise-a-minke-whale\/18-12\/\" class=\"wp-image-54041\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/18-12-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6.png\"><img width=\"800\" height=\"600\" src=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6.png\" alt=\"\" data-id=\"54043\" data-full-url=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6.png\" data-link=\"https:\/\/whalewatchingazores.com\/blog\/2020\/08\/5-cetacean-species-with-a-surprise-a-minke-whale\/22-6\/\" class=\"wp-image-54043\" srcset=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6.png 800w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6-300x225.png 300w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6-768x576.png 768w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6-200x150.png 200w, https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/22-6-380x285.png 380w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"Today we observed lots of biodiversity in the Azorean waters! Our small boats and our catamarans saw various&hellip;\n","protected":false},"author":4,"featured_media":54028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[308,393],"tags":[606,355,353,622,14,26,52,12,15,356],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 cetacean species with a surprise: a Minke whale! - Azores Whales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 cetacean species with a surprise: a Minke whale! - Azores Whales\" \/>\n<meta property=\"og:description\" content=\"Today we observed lots of biodiversity in the Azorean waters! Our small boats and our catamarans saw various&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/\" \/>\n<meta property=\"og:site_name\" content=\"Azores Whales\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-31T15:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-31T16:08:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/minke_whale4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#website\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"name\":\"Azores Whales\",\"description\":\"Azores Whale Watching Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/whalewatchingazores.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/minke_whale4.jpg\",\"contentUrl\":\"https:\/\/whalewatchingazores.com\/blog\/wp-content\/uploads\/2020\/08\/minke_whale4.jpg\",\"width\":800,\"height\":600},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/#webpage\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/\",\"name\":\"5 cetacean species with a surprise: a Minke whale! - Azores Whales\",\"isPartOf\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/#primaryimage\"},\"datePublished\":\"2020-08-31T15:10:00+00:00\",\"dateModified\":\"2020-08-31T16:08:00+00:00\",\"author\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#\/schema\/person\/5333e28d8775f800958b31c2212b7e4d\"},\"breadcrumb\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"url\":\"https:\/\/whalewatchingazores.com\/blog\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/5-cetacean-species-with-a-surprise-a-minke-whale\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#\/schema\/person\/5333e28d8775f800958b31c2212b7e4d\",\"name\":\"Futurismo Biologists Team\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/whalewatchingazores.com\/blog\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5dfccb8aa62f8fbea12a70b88219a100?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5dfccb8aa62f8fbea12a70b88219a100?s=96&d=mm&r=g\",\"caption\":\"Futurismo Biologists Team\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts\/53997"}],"collection":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/comments?post=53997"}],"version-history":[{"count":2,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts\/53997\/revisions"}],"predecessor-version":[{"id":54045,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/posts\/53997\/revisions\/54045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/media\/54028"}],"wp:attachment":[{"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/media?parent=53997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/categories?post=53997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/whalewatchingazores.com\/blog\/wp-json\/wp\/v2\/tags?post=53997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}